{"id":8441,"date":"2017-06-05T12:49:05","date_gmt":"2017-06-05T12:49:05","guid":{"rendered":"https:\/\/appnoticias.com.ar\/app\/?p=8441"},"modified":"2017-06-05T12:49:05","modified_gmt":"2017-06-05T12:49:05","slug":"el-frente-para-la-victoria-inicio-el-camino-a-las-paso-del-13-de-agosto","status":"publish","type":"post","link":"https:\/\/appnoticias.com.ar\/app\/el-frente-para-la-victoria-inicio-el-camino-a-las-paso-del-13-de-agosto\/","title":{"rendered":"El Frente para la Victoria inici\u00f3 el camino a las PASO del 13 de agosto"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>Choele Choel.-\u00a0(APP) Despu\u00e9s de ratificar la alianza entre sus nueve fuerzas, el Frente para la Victoria inici\u00f3 el camino a las PASO del 13 de agosto.<\/p>\n<p>\u201cUn 2 de junio del a\u00f1o pasado vino Bullrich a relanzar la campa\u00f1a del desierto en Choele Choel. Y nosotros hacemos lo contrario. En esta misma fecha se est\u00e1 lanzando por primera vez en todo el territorio nacional, la defensa de todos los rionegrinos\u201d, sostuvo el presidente del PJ, Mart\u00edn Soria.<\/p>\n<p>A este Frente para la Victoria se sumaron Forja y el Partido Comunista, mientras que contin\u00faan Kolina, Nuevo Encuentro, MAD, Frente Ciudadano, Movimiento Evita y La Campora.<\/p>\n<p>\u201cA Macri y Weretilneck los rionegrinos les van a hacer saber lo mal que est\u00e1n gobernando, los van a castigar en las urnas por la inflaci\u00f3n, el desempleo, el aumento de la pobreza y ahora tambi\u00e9n por querer convertir a R\u00edo Negro en Chernobyl\u201d, subray\u00f3 Soria.<\/p>\n<p>Luego de la firma del acta constitutiva del FpV, el Justicialismo ratific\u00f3 esta decisi\u00f3n en la reuni\u00f3n del Consejo Partidario del PJ, que se celebr\u00f3 en la previa a un acto partidario en el sal\u00f3n de la C\u00e1mara de Comercio de Choele Choel. Participaron de la firma del acta constitutiva del FpV, el presidente del PJ, Mart\u00edn Soria, el vicepresidente del PJ, Daniel Belloso, el presidente del Frente Grande, Julio Acavallo, el presidente del MAD, Diego Iraldi, Maria In\u00e9s Grandoso por Kolina, Matias Chironi por Nuevo Encuentro, Silvia Horme del Movimiento Evita, Elvin Willians por La Campora, Jos\u00e9 Luis Garc\u00eda Palazon referente por MNA-FORJA y B\u00e1rbara Palumbo por el Partido Comunista.<\/p>\n<p>Fuente: Diario R\u00edo Negro<\/p>\n","protected":false},"excerpt":{"rendered":"&nbsp; Choele Choel.-\u00a0(APP) Despu\u00e9s de ratificar la alianza entre sus nueve fuerzas, el Frente para la Victoria inici\u00f3 el camino a las PASO \n<a class=\"moretag\" href=\"https:\/\/appnoticias.com.ar\/app\/el-frente-para-la-victoria-inicio-el-camino-a-las-paso-del-13-de-agosto\/\"> [...]<\/a>","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-8441","post","type-post","status-publish","format-standard","hentry","category-politica"],"_links":{"self":[{"href":"https:\/\/appnoticias.com.ar\/app\/wp-json\/wp\/v2\/posts\/8441","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/appnoticias.com.ar\/app\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/appnoticias.com.ar\/app\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/appnoticias.com.ar\/app\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/appnoticias.com.ar\/app\/wp-json\/wp\/v2\/comments?post=8441"}],"version-history":[{"count":1,"href":"https:\/\/appnoticias.com.ar\/app\/wp-json\/wp\/v2\/posts\/8441\/revisions"}],"predecessor-version":[{"id":8443,"href":"https:\/\/appnoticias.com.ar\/app\/wp-json\/wp\/v2\/posts\/8441\/revisions\/8443"}],"wp:attachment":[{"href":"https:\/\/appnoticias.com.ar\/app\/wp-json\/wp\/v2\/media?parent=8441"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/appnoticias.com.ar\/app\/wp-json\/wp\/v2\/categories?post=8441"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/appnoticias.com.ar\/app\/wp-json\/wp\/v2\/tags?post=8441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}