{"id":8447,"date":"2017-06-05T12:57:35","date_gmt":"2017-06-05T12:57:35","guid":{"rendered":"https:\/\/appnoticias.com.ar\/app\/?p=8447"},"modified":"2017-06-05T12:57:35","modified_gmt":"2017-06-05T12:57:35","slug":"serios-destrozos-y-robo-de-elementos-en-la-delegacion-de-desarrollo-social-en-roca-tras-ocupacion","status":"publish","type":"post","link":"https:\/\/appnoticias.com.ar\/app\/serios-destrozos-y-robo-de-elementos-en-la-delegacion-de-desarrollo-social-en-roca-tras-ocupacion\/","title":{"rendered":"Serios destrozos y robo de elementos en la Delegaci\u00f3n de Desarrollo Social en Roca tras ocupaci\u00f3n"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><em>Viedma.- (APP) Serios destrozos en las instalaciones y el robo de mobiliario y otros elementos, tanto de la dependencia como de los propios trabajadores, fue el resultado de la ocupaci\u00f3n de las oficinas del Ministerio de Desarrollo Social en General Roca.<\/em><\/p>\n<p><em>\u00a0<\/em>La sede fue ocupada por la Organizaci\u00f3n de Desocupados en Lucha (ODEL), generando adem\u00e1s la paralizaci\u00f3n de las actividades del organismo p\u00fablico por casi un mes.<\/p>\n<p>La situaci\u00f3n fue denunciada por el propio ministro de Desarrollo Social, Fabi\u00e1n Galli, quien dio cuenta del faltante de equipos inform\u00e1ticos con valiosa informaci\u00f3n, mobiliarios y distintos elementos de la Delegaci\u00f3n, as\u00ed como la destrucci\u00f3n de paredes e instalaciones, la pintada de paredes y otras cuestiones que demandar\u00e1n un importante gasto al erario p\u00fablico provincial. Se constat\u00f3 la falta adem\u00e1s de colchones, alimentos y bienes personales de los trabajadores.<\/p>\n<p>No obstante, el funcionario provincial lament\u00f3 adem\u00e1s de los da\u00f1os y gastos econ\u00f3micos, que la toma del edificio por parte de la Organizaci\u00f3n de Desocupados en Lucha (ODEL) signific\u00f3 la par\u00e1lisis total de este organismo provincial durante un mes, \u201cimpidiendo el normal trabajo y la asistencia a las familias de General Roca y la regi\u00f3n que necesitan del acompa\u00f1amiento del Estado\u201d. \u201cParece mentira que aduciendo la supuesta necesidad de ayuda, impidan que otros vecinos puedan acceder a la contenci\u00f3n que necesitan\u201d, dijo Galli.<\/p>\n<p>Agreg\u00f3 que \u201cno quedan dudas que esto fue una acci\u00f3n pol\u00edtica disfrazada detr\u00e1s de un supuesto reclamo social. El l\u00edder de ODEL es uno de los socios pol\u00edticos de Rodolfo Aguiar y ATE, y prueba de ello es su activa participaci\u00f3n en la agresi\u00f3n a polic\u00edas ocurrida d\u00edas atr\u00e1s en Viedma frente a la Legislatura. Mientras B\u00e1ez sigue pr\u00f3fugo, su grupo sigui\u00f3 ocupando y destruyendo nuestras oficinas\u201d.<\/p>\n<p>\u201cEsto no tiene nada que ver con necesidades sociales. Tiene un \u00fanico fin que es evitar el funcionamiento del sistema de asistencia a las familias de la regi\u00f3n con necesidades. Cada pedido realizado por la Organizaci\u00f3n de Desocupados en Lucha por los caminos que corresponde han sido atendidos y han recibido la asistencia requerida y comprometida por el Ministerio. Ahora, cuando los pedidos no son a trav\u00e9s de los mecanismos naturales y encima pretenden lograr lo que quieren mediante el uso de la fuerza y la destrucci\u00f3n, es imposible que se pueda avanzar en soluciones\u201d, dijo.<\/p>\n<p>El Ministro agreg\u00f3 que \u201cesto no es m\u00e1s que un acto vand\u00e1lico te\u00f1ido de cuestiones pol\u00edticas, y jam\u00e1s cederemos ante la extorsi\u00f3n, sea cual sea el m\u00e9todo utilizado. Denunciamos esta situaci\u00f3n y avanzaremos hasta las \u00faltimas consecuencias\u201d.<\/p>\n<p>Por otra parte, Galli lament\u00f3 la poca respuesta obtenida de parte de la Justicia, que no tom\u00f3 la debida intervenci\u00f3n para normalizar la situaci\u00f3n tras la toma del edificio por un mes. Cit\u00f3 al juez Maximiliano Camarda y al Fiscal Ricardo Romero, ya que desde el Ministerio se realizaron distintas denuncias durante la ocupaci\u00f3n y nunca accionaron para descomprimir el conflicto. \u00abEspero que a partir de estas denuncias act\u00faen en consecuencia\u00bb, indic\u00f3 finalmente.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"&nbsp; &nbsp; Viedma.- (APP) Serios destrozos en las instalaciones y el robo de mobiliario y otros elementos, tanto de la dependencia como de \n<a class=\"moretag\" href=\"https:\/\/appnoticias.com.ar\/app\/serios-destrozos-y-robo-de-elementos-en-la-delegacion-de-desarrollo-social-en-roca-tras-ocupacion\/\"> [...]<\/a>","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-8447","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/appnoticias.com.ar\/app\/wp-json\/wp\/v2\/posts\/8447","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/appnoticias.com.ar\/app\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/appnoticias.com.ar\/app\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/appnoticias.com.ar\/app\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/appnoticias.com.ar\/app\/wp-json\/wp\/v2\/comments?post=8447"}],"version-history":[{"count":1,"href":"https:\/\/appnoticias.com.ar\/app\/wp-json\/wp\/v2\/posts\/8447\/revisions"}],"predecessor-version":[{"id":8449,"href":"https:\/\/appnoticias.com.ar\/app\/wp-json\/wp\/v2\/posts\/8447\/revisions\/8449"}],"wp:attachment":[{"href":"https:\/\/appnoticias.com.ar\/app\/wp-json\/wp\/v2\/media?parent=8447"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/appnoticias.com.ar\/app\/wp-json\/wp\/v2\/categories?post=8447"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/appnoticias.com.ar\/app\/wp-json\/wp\/v2\/tags?post=8447"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}